{"id":31675,"date":"2026-08-27T14:26:12","date_gmt":"2026-08-27T12:26:12","guid":{"rendered":"http:\/\/www.cobon1tp.it\/cobon1tp\/?post_type=albo_pretorio&#038;p=31675"},"modified":"2026-08-27T14:26:12","modified_gmt":"2026-08-27T12:26:12","slug":"liquidazione-e-pagamento-anticipazione-somme-alleconomo-dott-manuel-di-liberti-anno-2026","status":"publish","type":"amm_trasparente","link":"http:\/\/www.cobon1tp.it\/cobon1tp\/amm_trasparente\/liquidazione-e-pagamento-anticipazione-somme-alleconomo-dott-manuel-di-liberti-anno-2026\/","title":{"rendered":"Liquidazione e pagamento &#8211; Anticipazione somme all&#8217;economo dott. Manuel Di Liberti &#8211; anno 2026"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","categoria_albo_pretorio":[316,318],"acf":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"large-thumb":false,"mansory-thumb":false,"single-alignfull-thumb":false,"sow-carousel-default":false},"uagb_author_info":{"display_name":"Rino Tigri","author_link":"http:\/\/www.cobon1tp.it\/cobon1tp\/author\/"},"uagb_comment_info":0,"uagb_excerpt":null,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v15.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>Liquidazione e pagamento - Anticipazione somme all&#039;economo dott. Manuel Di Liberti - anno 2026 - Consorzio di Bonifica 1 Trapani<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"http:\/\/www.cobon1tp.it\/cobon1tp\/albo_pretorio\/liquidazione-e-pagamento-anticipazione-somme-alleconomo-dott-manuel-di-liberti-anno-2026\/\" \/>\r\n<meta property=\"og:locale\" content=\"it_IT\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Liquidazione e pagamento - Anticipazione somme all&#039;economo dott. Manuel Di Liberti - anno 2026 - Consorzio di Bonifica 1 Trapani\" \/>\r\n<meta property=\"og:url\" content=\"http:\/\/www.cobon1tp.it\/cobon1tp\/albo_pretorio\/liquidazione-e-pagamento-anticipazione-somme-alleconomo-dott-manuel-di-liberti-anno-2026\/\" \/>\r\n<meta property=\"og:site_name\" content=\"Consorzio di Bonifica 1 Trapani\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/www.cobon1tp.it\/cobon1tp\/#website\",\"url\":\"http:\/\/www.cobon1tp.it\/cobon1tp\/\",\"name\":\"Consorzio di Bonifica 1 Trapani\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"http:\/\/www.cobon1tp.it\/cobon1tp\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.cobon1tp.it\/cobon1tp\/albo_pretorio\/liquidazione-e-pagamento-anticipazione-somme-alleconomo-dott-manuel-di-liberti-anno-2026\/#webpage\",\"url\":\"http:\/\/www.cobon1tp.it\/cobon1tp\/albo_pretorio\/liquidazione-e-pagamento-anticipazione-somme-alleconomo-dott-manuel-di-liberti-anno-2026\/\",\"name\":\"Liquidazione e pagamento - Anticipazione somme all'economo dott. Manuel Di Liberti - anno 2026 - Consorzio di Bonifica 1 Trapani\",\"isPartOf\":{\"@id\":\"http:\/\/www.cobon1tp.it\/cobon1tp\/#website\"},\"datePublished\":\"2026-08-27T12:26:12+00:00\",\"dateModified\":\"2026-08-27T12:26:12+00:00\",\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.cobon1tp.it\/cobon1tp\/albo_pretorio\/liquidazione-e-pagamento-anticipazione-somme-alleconomo-dott-manuel-di-liberti-anno-2026\/\"]}]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"http:\/\/www.cobon1tp.it\/cobon1tp\/wp-json\/wp\/v2\/amm_trasparente\/31675"}],"collection":[{"href":"http:\/\/www.cobon1tp.it\/cobon1tp\/wp-json\/wp\/v2\/amm_trasparente"}],"about":[{"href":"http:\/\/www.cobon1tp.it\/cobon1tp\/wp-json\/wp\/v2\/types\/amm_trasparente"}],"wp:attachment":[{"href":"http:\/\/www.cobon1tp.it\/cobon1tp\/wp-json\/wp\/v2\/media?parent=31675"}],"wp:term":[{"taxonomy":"categoria_albo_pretorio","embeddable":true,"href":"http:\/\/www.cobon1tp.it\/cobon1tp\/wp-json\/wp\/v2\/categoria_albo_pretorio?post=31675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}